{"id":37,"date":"2017-02-27T20:40:30","date_gmt":"2017-02-27T19:40:30","guid":{"rendered":"https:\/\/kulturweit.blog\/thirstforadventure\/?p=37"},"modified":"2017-02-27T20:42:14","modified_gmt":"2017-02-27T19:42:14","slug":"spring-fever","status":"publish","type":"post","link":"https:\/\/kulturweit.blog\/thirstforadventure\/2017\/02\/27\/spring-fever\/","title":{"rendered":"Spring fever"},"content":{"rendered":"<p>Und dann sitze ich wieder hier, neben der kleinen Stra&szlig;enkatze mit dem gebrochenen Schwanz, die mich nicht verl&auml;sst, obwohl ich doch alles versucht habe. Selbst Wasser, vom Scho&szlig; schubsen und ignorieren hat nichts gebracht. Sie wird wohl f&uuml;r immer neben mir sitzen bleiben und es sich gemeinsam mit mir im Sonnenuntergang auf meiner Terrasse gem&uuml;tlich machen und den Beginn des Fr&uuml;hlings feiern. Vermutlich hat auch sie bemerkt, dass ich mich im Inneren doch ein kleines bisschen freue, wenn sie mal wieder vorbeischaut.<\/p>\n<blockquote>\n<p style=\"text-align: left\"><em>Ich bin zur&uuml;ck. <\/em><\/p>\n<p style=\"text-align: left\"><em>Ich bin zur&uuml;ck in Ulcinj. <\/em><\/p>\n<p style=\"text-align: left\"><em>Ich bin zur&uuml;ck zu Hause und in der Sonne. <\/em><\/p>\n<\/blockquote>\n<p>Monate sind seit meinem letzten Blogeintrag vergangen und das hat viele Gr&uuml;nde. Um es kurz zu machen: Ich war stark besch&auml;ftigt. Mit Weihnachten, Reisen nach Riga, Lettland und Tschechien, einer Auszeit vom st&uuml;rmischen Winter Ulcinjs in Berlin, meiner organisierten Klassenfahrt nach Berlin, mit der &nbsp;Austauschfahrt nach Freudenstadt im Schwarzwald, einer unvorhergesehenen Weisheitszahn-OP und dem Leben, das dann daneben noch so weiterl&auml;uft. F&uuml;r ein Update war keine Zeit.<\/p>\n<p>Nun, wieder zur&uuml;ck auf meiner Terrasse merke ich, dass ich wieder zur Ruhe komme. Es ist Ende Februar und ich sitze mit T-Shirt und kurzer Hose drau&szlig;en. Ich sp&uuml;re regelrecht wie mir diese W&auml;rme der Sonne guttut und bin dankbar f&uuml;r diese Stunden, in denen ich nichts tun muss. Ulcinj hat mich ver&auml;ndert, das wurde mir heute ganz bewusst als ich in die Schule ging. Ich bin selbstbewusster und noch offener geworden. Ich nehme das Leben hier an, so wie es ist, auch wenn es anders als mein Leben in Berlin ist. Und auch wenn Ulcinj eine kleine Stadt ist, eher ein Dorf, strahlt diese Stadt mehr Energie aus, als so mancher Ort in Deutschland. Wenn mir Sch&uuml;ler und Verk&auml;ufer herzlich zuwinken, wenn ich nach langer Zeit wieder durch die Stra&szlig;en laufe, meine Vermieter mich dann herzlich umarmen und alles vertraut ist, dann wei&szlig; ich, dass ich wieder zuhause bin.<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-39 alignleft\" src=\"https:\/\/kulturweit.blog\/thirstforadventure\/files\/2017\/02\/16997389_766118760203691_912287360_n-300x242.jpg\" alt=\"\" width=\"300\" height=\"242\" srcset=\"https:\/\/kulturweit.blog\/thirstforadventure\/files\/2017\/02\/16997389_766118760203691_912287360_n-300x242.jpg 300w, https:\/\/kulturweit.blog\/thirstforadventure\/files\/2017\/02\/16997389_766118760203691_912287360_n-768x619.jpg 768w, https:\/\/kulturweit.blog\/thirstforadventure\/files\/2017\/02\/16997389_766118760203691_912287360_n-750x605.jpg 750w, https:\/\/kulturweit.blog\/thirstforadventure\/files\/2017\/02\/16997389_766118760203691_912287360_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Leni<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Und dann sitze ich wieder hier, neben der kleinen Stra&szlig;enkatze mit dem gebrochenen Schwanz, die mich nicht verl&auml;sst, obwohl ich doch alles versucht habe. Selbst Wasser, vom Scho&szlig; schubsen und ignorieren hat nichts gebracht. Sie wird wohl f&uuml;r immer neben &hellip; <a href=\"https:\/\/kulturweit.blog\/thirstforadventure\/2017\/02\/27\/spring-fever\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1968,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-37","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/posts\/37"}],"collection":[{"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/users\/1968"}],"replies":[{"embeddable":true,"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":4,"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"predecessor-version":[{"id":48,"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/posts\/37\/revisions\/48"}],"wp:attachment":[{"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kulturweit.blog\/thirstforadventure\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}